{"id":9,"count":22,"description":"","link":"https:\/\/islandapadvanced.ulpgc.es\/pt\/tag\/ulpgc\/","name":"ULPGC","slug":"ulpgc","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ULPGC archivos - Islandap Advanced<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ULPGC archivos - Islandap Advanced\" \/>\n<meta property=\"og:url\" content=\"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/\" \/>\n<meta property=\"og:site_name\" content=\"Islandap Advanced\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/\",\"url\":\"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/\",\"name\":\"ULPGC archivos - Islandap Advanced\",\"isPartOf\":{\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/#breadcrumb\"},\"inLanguage\":\"pt-PT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/islandapadvanced.ulpgc.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ULPGC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/#website\",\"url\":\"https:\/\/islandapadvanced.ulpgc.es\/\",\"name\":\"Islandap Advanced\",\"description\":\"R+D+i Towards Aquaponic Development in the Up Islands and the Circular Economy\",\"publisher\":{\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/islandapadvanced.ulpgc.es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/#organization\",\"name\":\"Proyecto Islandap Advanced de la Universidad de Las Palmas de Gran Canaria\",\"url\":\"https:\/\/islandapadvanced.ulpgc.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/islandapadvanced.ulpgc.es\/wp-content\/uploads\/2021\/07\/logo_islandap_advanced.svg\",\"contentUrl\":\"https:\/\/islandapadvanced.ulpgc.es\/wp-content\/uploads\/2021\/07\/logo_islandap_advanced.svg\",\"width\":1,\"height\":1,\"caption\":\"Proyecto Islandap Advanced de la Universidad de Las Palmas de Gran Canaria\"},\"image\":{\"@id\":\"https:\/\/islandapadvanced.ulpgc.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ULPGC archivos - Islandap Advanced","robots":{"index":"noindex","follow":"follow"},"og_locale":"pt_PT","og_type":"article","og_title":"ULPGC archivos - Islandap Advanced","og_url":"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/","og_site_name":"Islandap Advanced","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/","url":"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/","name":"ULPGC archivos - Islandap Advanced","isPartOf":{"@id":"https:\/\/islandapadvanced.ulpgc.es\/#website"},"breadcrumb":{"@id":"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/#breadcrumb"},"inLanguage":"pt-PT"},{"@type":"BreadcrumbList","@id":"https:\/\/islandapadvanced.ulpgc.es\/tag\/ulpgc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/islandapadvanced.ulpgc.es\/"},{"@type":"ListItem","position":2,"name":"ULPGC"}]},{"@type":"WebSite","@id":"https:\/\/islandapadvanced.ulpgc.es\/#website","url":"https:\/\/islandapadvanced.ulpgc.es\/","name":"Islandap Advanced","description":"R+D+i Towards Aquaponic Development in the Up Islands and the Circular Economy","publisher":{"@id":"https:\/\/islandapadvanced.ulpgc.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/islandapadvanced.ulpgc.es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/islandapadvanced.ulpgc.es\/#organization","name":"Proyecto Islandap Advanced de la Universidad de Las Palmas de Gran Canaria","url":"https:\/\/islandapadvanced.ulpgc.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/islandapadvanced.ulpgc.es\/#\/schema\/logo\/image\/","url":"https:\/\/islandapadvanced.ulpgc.es\/wp-content\/uploads\/2021\/07\/logo_islandap_advanced.svg","contentUrl":"https:\/\/islandapadvanced.ulpgc.es\/wp-content\/uploads\/2021\/07\/logo_islandap_advanced.svg","width":1,"height":1,"caption":"Proyecto Islandap Advanced de la Universidad de Las Palmas de Gran Canaria"},"image":{"@id":"https:\/\/islandapadvanced.ulpgc.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/islandapadvanced.ulpgc.es\/pt\/wp-json\/wp\/v2\/tags\/9"}],"collection":[{"href":"https:\/\/islandapadvanced.ulpgc.es\/pt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/islandapadvanced.ulpgc.es\/pt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/islandapadvanced.ulpgc.es\/pt\/wp-json\/wp\/v2\/posts?tags=9"},{"href":"https:\/\/islandapadvanced.ulpgc.es\/pt\/wp-json\/wp\/v2\/pec-events?tags=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}